{"id":484,"date":"2023-10-22T21:59:32","date_gmt":"2023-10-22T21:59:32","guid":{"rendered":"https:\/\/t-rexservices.be\/over-ons\/"},"modified":"2024-01-03T21:55:06","modified_gmt":"2024-01-03T21:55:06","slug":"ueber-uns","status":"publish","type":"page","link":"https:\/\/t-rexservices.be\/de\/ueber-uns\/","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_6df4bc3a subpage-header has_text_color height_large with_img\"><div class=\"l-section-img\" role=\"img\" aria-label=\"Bild\" data-img-width=\"1920\" data-img-height=\"428\" style=\"background-image: url(https:\/\/t-rexservices.be\/wp-content\/uploads\/2023\/10\/header.jpg);\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_eb849559\"><div class=\"wpb_wrapper\"><h1>T-Rex Dienstleistungen: Experte in der Begleitung von au\u00dfergew\u00f6hnlichen Transporten<\/h1>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_19737bc8 height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default stacking_default\"><div class=\"wpb_column vc_column_container us_custom_7e20fa79 content-sp us_animate_this\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_2305fb60 h2-line-btm ul-sp\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: left;\">Erfahrung und Knowhow<\/h2>\n<p>Im Jahr 2010 erblickte T-Rex Services das Licht der Welt. Direktor Toon Janssens hatte zu diesem Zeitpunkt bereits jahrelange Erfahrung in diesem Sektor gesammelt. Es war an der Zeit, diese Erfahrung in einem eigenen Unternehmen noch besser zu nutzen. So k\u00f6nnen wir auf eine mehr als 25-j\u00e4hrige Erfahrung im Bereich der Sondertransporte zur\u00fcckblicken.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_51a49280 min-h-sp us_animate_this has_bg_color stretched\"><div class=\"vc_column-inner\"><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_aa29dcc4 height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default reversed stacking_default\"><div class=\"wpb_column vc_column_container us_custom_50b98729 min-h-sp us_animate_this has_bg_color stretched\"><div class=\"vc_column-inner\"><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_47474b22 content-sp us_animate_this\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_ea536bc7 h2-line-btm ul-sp\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: left;\">Familienunternehmen von Vater und Sohn<\/h2>\n<p>Wir erweitern dieses Wissen und diese Erfahrung jeden Tag. Und das nicht mehr allein, denn seit einigen Jahren ist T-Rex Service zu einem Familienunternehmen geworden. Auch Sohn Kenzo Janssens tr\u00e4gt zum weiteren Ausbau von T-Rex Services bei. Kenzo wurde die Liebe zur Begleitung von Sondertransporten in die Wiege gelegt, und er f\u00fchlt die gleiche Leidenschaft f\u00fcr diesen Beruf wie sein Vater Toon.<br \/>\nSeit letztem Jahr hat T-Rex Services seine Dienstleistungen um Streckenma\u00dfnahmen erweitert: Anpassung der Stra\u00dfeninfrastruktur f\u00fcr Sondertransporte. Mit dieser Kombination sind wir in Belgien einzigartig.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_ec8580f4 cta-middle height_large width_custom\" style=\"--site-content-width:1000px;\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1-3 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default stacking_default\"><div class=\"wpb_column vc_column_container us_custom_7e20fa79 us_animate_this\"><div class=\"vc_column-inner\"><div class=\"w-image us_custom_1d1c165d align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"2000\" height=\"2000\" src=\"https:\/\/t-rexservices.be\/wp-content\/uploads\/2023\/10\/illustration.svg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" \/><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_47474b22 us_animate_this\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_3415c6d7 h2-line-btm has_text_color\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: left;\">Unser fantastisches Team<\/h2>\n<p>F\u00fcr die Begleitung von Sondertransporten haben wir ein fantastisches Team mit etwa 10 Begleitfahrzeugen. Sie kennen die Tricks und Kniffe der Branche und k\u00f6nnen alle auf jahrelange Erfahrung zur\u00fcckblicken. Wir arbeiten auch sehr gut mit einem festen Partner zusammen, der ebenfalls ein Spezialist f\u00fcr Sondertransporte ist.<br \/>\nIn der Verwaltung werden Toon und Kenzo zudem von Sandra unterst\u00fctzt. Sie ist die freundliche, hilfsbereite Stimme, die man bei Verwaltungsangelegenheiten am Telefon h\u00f6rt.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default stacking_default\"><div class=\"wpb_column vc_column_container us_custom_7e20fa79 content-sp us_animate_this\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_2305fb60 h2-line-btm ul-sp\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: left;\">T-Rex Begeleidingen in den Niederlanden<\/h2>\n<p>Auch in den Niederlanden gibt es T-Rex Services. Wir haben dort eine eigene Niederlassung mit der n\u00f6tigen Expertise f\u00fcr die Niederlande. Unsere Mitarbeiter dort kennen das niederl\u00e4ndische Stra\u00dfennetz im Detail und helfen Ihnen mit den notwendigen Ausnahmen und Begleitanliegen. So vermeiden Sie zus\u00e4tzliche Transitkosten. Die Kontaktdaten unserer niederl\u00e4ndischen Firma finden Sie auf der Kontaktseite.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_61cdba54 min-h-sp us_animate_this has_bg_color stretched\"><div class=\"vc_column-inner\"><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_ff551dff height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default reversed stacking_default\"><div class=\"wpb_column vc_column_container us_custom_409e9f65 min-h-sp us_animate_this has_bg_color stretched\"><div class=\"vc_column-inner\"><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_47474b22 content-sp us_animate_this\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_ea536bc7 h2-line-btm ul-sp\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: left;\">Moderne und hochtechnologische Einrichtungen und Kommunikationskan\u00e4le<\/h2>\n<p>Wir nutzen die modernen, hochtechnologischen Einrichtungen und Kommunikationskan\u00e4le, die derzeit zur Verf\u00fcgung stehen, intelligent und effizient. Wir haben auch unsere eigenen Karten auf Papier. Darauf sind alle Routennetze in verschiedenen Farben aufgedruckt. Dies kann f\u00fcr Fahrer n\u00fctzlich sein, die keine Begleitung ben\u00f6tigen. Sind Sie interessiert? Informieren Sie uns gerne.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_9dfb8529 cta-middle height_large width_custom\" style=\"--site-content-width:900px;\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_3415c6d7 h2-line-btm has_text_color\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center;\">Immer f\u00fcr Sie bereit und verf\u00fcgbar<\/h2>\n<p>Wir sind immer in Bereitschaft. Wenn Ihr Transport unterwegs ist, k\u00f6nnen Sie uns jederzeit telefonisch erreichen. Und Sie sind auch in unserem B\u00fcro willkommen. Wir hatten fr\u00fcher ein kleines B\u00fcro in Aartselaar. Jetzt finden Sie uns in einer strategischen g\u00fcnstigen Lage am Stadtrand von Antwerpen, in der N\u00e4he des Hafens. M\u00f6chten Sie mit uns \u00fcber eine m\u00f6gliche Zusammenarbeit sprechen? Wir w\u00fcrden uns freuen, Sie in unserem B\u00fcro begr\u00fc\u00dfen zu d\u00fcrfen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default stacking_default\"><div class=\"wpb_column vc_column_container us_custom_7e20fa79 content-sp us_animate_this\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_2305fb60 h2-line-btm ul-sp\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: left;\">Pr\u00e4zision und Sicherheit gehen vor!<\/h2>\n<p>Unsere Arbeit erfordert vor allem Pr\u00e4zision, P\u00fcnktlichkeit und Sicherheit. Daf\u00fcr setzen wir uns voll ein. Wenn wir Ihren Sondertransport begleiten, dann tun wir das in hervorragender Weise, wobei Pr\u00e4zision und Sicherheit an erster Stelle stehen.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_71eaa218 min-h-sp us_animate_this has_bg_color stretched\"><div class=\"vc_column-inner\"><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_ff551dff height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default reversed stacking_default\"><div class=\"wpb_column vc_column_container us_custom_306bd681 min-h-sp us_animate_this has_bg_color stretched\"><div class=\"vc_column-inner\"><\/div><\/div><div class=\"wpb_column vc_column_container us_custom_47474b22 content-sp us_animate_this\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_ea536bc7 h2-line-btm ul-sp\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: left;\">Kein Transport ist zu gro\u00df f\u00fcr uns!<\/h2>\n<p>Nicht umsonst ist unser Logo ein T-Rex. Ein T-Rex ist gro\u00df und gigantisch stark. Das wollen wir auch f\u00fcr Sie und Ihre Fracht sein. Egal wie lang, wie hoch, wie schwer oder wie breit Ihre zu transportierende Ladung ist, wir regeln es f\u00fcr Sie! Wir finden immer eine L\u00f6sung, um Ihren Sondertransport in ganz Europa mit den richtigen Genehmigungen und der perfekten Begleitung zu organisieren. Wir verf\u00fcgen \u00fcber neue, leistungsstarke Begleitfahrzeuge und die notwendige Ausr\u00fcstung, um den Weg f\u00fcr Ihren Transport frei zu machen!<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_d5db684f cta-bottom height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default stacking_default\"><div class=\"wpb_column vc_column_container us_custom_eb849559\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_7c5f6a71 pyellow\"><div class=\"wpb_wrapper\"><p>Weitere Fragen? Weitere Informationen? Ein ma\u00dfgeschneidertes Angebot f\u00fcr Ihren Sondertransport?<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_a8d28062 cta-b has_text_color\"><div class=\"wpb_wrapper\"><p>T-Rex Services hilft Ihnen professionell und schnell!<br \/>\nKontaktieren Sie uns per E-Mail oder rufen Sie uns an unter <strong>+32 (0) 369 70 50<\/strong>, um ein ma\u00dfgeschneidertes Angebot zu erhalten.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_center\"><a class=\"w-btn us-btn-style_1\" href=\"https:\/\/t-rexservices.be\/de\/kontakt\/\"><span class=\"w-btn-label\">Kontaktieren Sie uns<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"T-Rex Dienstleistungen: Experte in der Begleitung von au\u00dfergew\u00f6hnlichen Transporten Erfahrung und Knowhow Im Jahr 2010 erblickte T-Rex Services das Licht der Welt. Direktor Toon Janssens hatte zu diesem Zeitpunkt bereits jahrelange Erfahrung in diesem Sektor gesammelt. Es war an der Zeit, diese Erfahrung in einem eigenen Unternehmen noch besser zu nutzen. So k\u00f6nnen wir auf...","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-484","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T-Rex Services | Familienunternehmen | T-Rex Services Belgien und Niederlande<\/title>\n<meta name=\"description\" content=\"T-Rex Services ist ein Familienunternehmen mit jahrzehntelanger Erfahrung in der Begleitung von Sondertransporten und den damit verbundenen Genehmigungen. Rufen Sie uns an: +32 (0)3 369 70 50.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/t-rexservices.be\/over-ons\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T-Rex Services | Familienunternehmen | T-Rex Services Belgien und Niederlande\" \/>\n<meta property=\"og:description\" content=\"T-Rex Services ist ein Familienunternehmen mit jahrzehntelanger Erfahrung in der Begleitung von Sondertransporten und den damit verbundenen Genehmigungen. Rufen Sie uns an: +32 (0)3 369 70 50.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/t-rexservices.be\/over-ons\/\" \/>\n<meta property=\"og:site_name\" content=\"T-Rex Services\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-03T21:55:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/t-rexservices.be\/wp-content\/uploads\/2023\/10\/trex-fb-picture.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"418\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/t-rexservices.be\/over-ons\/\",\"url\":\"https:\/\/t-rexservices.be\/over-ons\/\",\"name\":\"T-Rex Services | Familienunternehmen | T-Rex Services Belgien und Niederlande\",\"isPartOf\":{\"@id\":\"https:\/\/t-rexservices.be\/#website\"},\"datePublished\":\"2023-10-22T21:59:32+00:00\",\"dateModified\":\"2024-01-03T21:55:06+00:00\",\"description\":\"T-Rex Services ist ein Familienunternehmen mit jahrzehntelanger Erfahrung in der Begleitung von Sondertransporten und den damit verbundenen Genehmigungen. Rufen Sie uns an: +32 (0)3 369 70 50.\",\"breadcrumb\":{\"@id\":\"https:\/\/t-rexservices.be\/over-ons\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/t-rexservices.be\/over-ons\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/t-rexservices.be\/over-ons\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/t-rexservices.be\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber uns\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/t-rexservices.be\/#website\",\"url\":\"https:\/\/t-rexservices.be\/\",\"name\":\"T-Rex Services\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/t-rexservices.be\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T-Rex Services | Familienunternehmen | T-Rex Services Belgien und Niederlande","description":"T-Rex Services ist ein Familienunternehmen mit jahrzehntelanger Erfahrung in der Begleitung von Sondertransporten und den damit verbundenen Genehmigungen. Rufen Sie uns an: +32 (0)3 369 70 50.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/t-rexservices.be\/over-ons\/","og_locale":"de_DE","og_type":"article","og_title":"T-Rex Services | Familienunternehmen | T-Rex Services Belgien und Niederlande","og_description":"T-Rex Services ist ein Familienunternehmen mit jahrzehntelanger Erfahrung in der Begleitung von Sondertransporten und den damit verbundenen Genehmigungen. Rufen Sie uns an: +32 (0)3 369 70 50.","og_url":"https:\/\/t-rexservices.be\/over-ons\/","og_site_name":"T-Rex Services","article_modified_time":"2024-01-03T21:55:06+00:00","og_image":[{"width":800,"height":418,"url":"https:\/\/t-rexservices.be\/wp-content\/uploads\/2023\/10\/trex-fb-picture.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/t-rexservices.be\/over-ons\/","url":"https:\/\/t-rexservices.be\/over-ons\/","name":"T-Rex Services | Familienunternehmen | T-Rex Services Belgien und Niederlande","isPartOf":{"@id":"https:\/\/t-rexservices.be\/#website"},"datePublished":"2023-10-22T21:59:32+00:00","dateModified":"2024-01-03T21:55:06+00:00","description":"T-Rex Services ist ein Familienunternehmen mit jahrzehntelanger Erfahrung in der Begleitung von Sondertransporten und den damit verbundenen Genehmigungen. Rufen Sie uns an: +32 (0)3 369 70 50.","breadcrumb":{"@id":"https:\/\/t-rexservices.be\/over-ons\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/t-rexservices.be\/over-ons\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/t-rexservices.be\/over-ons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/t-rexservices.be\/de\/"},{"@type":"ListItem","position":2,"name":"\u00dcber uns"}]},{"@type":"WebSite","@id":"https:\/\/t-rexservices.be\/#website","url":"https:\/\/t-rexservices.be\/","name":"T-Rex Services","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/t-rexservices.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/t-rexservices.be\/de\/wp-json\/wp\/v2\/pages\/484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/t-rexservices.be\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/t-rexservices.be\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/t-rexservices.be\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/t-rexservices.be\/de\/wp-json\/wp\/v2\/comments?post=484"}],"version-history":[{"count":2,"href":"https:\/\/t-rexservices.be\/de\/wp-json\/wp\/v2\/pages\/484\/revisions"}],"predecessor-version":[{"id":490,"href":"https:\/\/t-rexservices.be\/de\/wp-json\/wp\/v2\/pages\/484\/revisions\/490"}],"wp:attachment":[{"href":"https:\/\/t-rexservices.be\/de\/wp-json\/wp\/v2\/media?parent=484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}